{"id":7394,"date":"2019-06-05T09:05:55","date_gmt":"2019-06-05T08:05:55","guid":{"rendered":"https:\/\/lopezdearenas.org\/inicio\/blog\/?p=7394"},"modified":"2019-06-05T09:09:29","modified_gmt":"2019-06-05T08:09:29","slug":"defensa-de-proyectos-finalistas-jovemprende-xi-edicion","status":"publish","type":"post","link":"https:\/\/lopezdearenas.org\/inicio\/blog\/defensa-de-proyectos-finalistas-jovemprende-xi-edicion\/","title":{"rendered":"Defensa de proyectos finalistas &#8211; Jovemprende XI Edici\u00f3n"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1502\" height=\"288\" src=\"https:\/\/i0.wp.com\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/jovemprende.png?fit=584%2C112&amp;ssl=1\" alt=\"\" class=\"wp-image-7395\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/jovemprende.png 1502w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/jovemprende-300x58.png 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/jovemprende-768x147.png 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/jovemprende-1024x196.png 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/jovemprende-500x96.png 500w\" sizes=\"auto, (max-width: 1502px) 100vw, 1502px\" \/><\/figure>\n\n\n\n<p>El orden de intervenciones para la defensa de los proyectos finalistas de la XI Edici\u00f3n  de Jovemprende que tendr\u00e1 lugar el viernes 7 de junio, es el siguiente:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"3508\" height=\"2479\" src=\"https:\/\/i0.wp.com\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/intervenciones-GS.jpg?fit=584%2C413&amp;ssl=1\" alt=\"\" class=\"wp-image-7396\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/intervenciones-GS.jpg 3508w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/intervenciones-GS-300x212.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/intervenciones-GS-768x543.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/intervenciones-GS-1024x724.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/intervenciones-GS-425x300.jpg 425w\" sizes=\"auto, (max-width: 3508px) 100vw, 3508px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"3508\" height=\"2479\" src=\"https:\/\/i1.wp.com\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/intervenciones-GM.jpg?fit=584%2C413&amp;ssl=1\" alt=\"\" class=\"wp-image-7397\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/intervenciones-GM.jpg 3508w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/intervenciones-GM-300x212.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/intervenciones-GM-768x543.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/intervenciones-GM-1024x724.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2019\/06\/intervenciones-GM-425x300.jpg 425w\" sizes=\"auto, (max-width: 3508px) 100vw, 3508px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El orden de intervenciones para la defensa de los proyectos finalistas de la XI Edici\u00f3n de Jovemprende que tendr\u00e1 lugar el viernes 7 de junio, es el siguiente:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[12,5],"tags":[84,45,18,22,23],"class_list":["post-7394","post","type-post","status-publish","format-standard","hentry","category-noticias_breves","category-novedades","tag-administrativo","tag-ciclos-formativos","tag-concurso","tag-emprender","tag-jovemprende"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/posts\/7394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/comments?post=7394"}],"version-history":[{"count":3,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/posts\/7394\/revisions"}],"predecessor-version":[{"id":7401,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/posts\/7394\/revisions\/7401"}],"wp:attachment":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/media?parent=7394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/categories?post=7394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/tags?post=7394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}