{"id":18035,"date":"2026-05-06T18:41:19","date_gmt":"2026-05-06T17:41:19","guid":{"rendered":"https:\/\/lopezdearenas.org\/inicio\/blog\/?p=18035"},"modified":"2026-05-06T19:02:26","modified_gmt":"2026-05-06T18:02:26","slug":"el-ies-lopez-de-arenas-brilla-en-la-fase-autonomica-del-torneo-de-debate-sevilla-tiene-nombre-de-marchena","status":"publish","type":"post","link":"https:\/\/lopezdearenas.org\/inicio\/blog\/el-ies-lopez-de-arenas-brilla-en-la-fase-autonomica-del-torneo-de-debate-sevilla-tiene-nombre-de-marchena\/","title":{"rendered":"El IES L\u00f3pez de Arenas brilla en la Fase Auton\u00f3mica del Torneo de Debate: Sevilla tiene nombre de Marchena"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.04.40-1024x768.jpeg\" alt=\"\" class=\"wp-image-18036\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.04.40-1024x768.jpeg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.04.40-300x225.jpeg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.04.40-768x576.jpeg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.04.40-1536x1152.jpeg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.04.40-400x300.jpeg 400w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.04.40.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>El 5 y 6 de mayo, Jerez de la Frontera se convirti\u00f3 en el epicentro de la palabra y el pensamiento cr\u00edtico en Andaluc\u00eda. El <strong>IES L\u00f3pez de Arenas<\/strong> acudi\u00f3 a la cita con una responsabilidad de altura: representar a la provincia de Sevilla tras habernos alzado como <strong>campeones provinciales<\/strong> tanto en <strong>Castellano<\/strong> como en <strong>Ingl\u00e9s<\/strong>.<\/p>\n\n\n\n<p>Nuestro equipo de debate en castellano realiz\u00f3 una actuaci\u00f3n memorable. Tras superar rondas de alt\u00edsimo nivel, qued\u00f3 en el primer puesto en la fase eliminatoria. No perdi\u00f3 ninguno de los tres debates que disput\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.22.49-1024x768.jpeg\" alt=\"\" class=\"wp-image-18039\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.22.49-1024x768.jpeg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.22.49-300x225.jpeg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.22.49-768x576.jpeg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.22.49-1536x1152.jpeg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.22.49-400x300.jpeg 400w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.22.49.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Luego el equipo cay\u00f3 en semifinales ante el representante de Ja\u00e9n (quien finalmente se alz\u00f3 con el campeonato). Sin embargo, para muchos de los asistentes y especialistas presentes, ese duelo fue considerado una \u00abfinal anticipada\u00bb. <\/p>\n\n\n\n<p>Especial menci\u00f3n merece nuestro exordio literario en ingl\u00e9s y en espa\u00f1ol sobre las Ciudades Invisibles, que dej\u00f3 prendado al jurado y al p\u00fablico, demostrando que en el IES L\u00f3pez de Arenas la oratoria se entiende como un arte que combina el rigor argumental con la belleza de la palabra.<\/p>\n\n\n\n<p>tenemos que a\u00f1adir que, en esta aventura auton\u00f3mica, compartimos expedici\u00f3n con el IES Fernando Herrera de Sevilla capital, representantes en la modalidad de Franc\u00e9s. Queremos felicitarles por su excelente papel como semifinalistas y, especialmente, a su alumna premiada como mejor oradora en dicha modalidad. Los tres equipos sevillanos demostraron que el nivel de nuestra provincia es, sencillamente, excepcional. Nos ha faltado muy poquito para alcanzar el \u00e9xito total.<\/p>\n\n\n\n<p>En fin, este crecimiento imparable y sostenido del IES L\u00f3pez de Arenas en relaci\u00f3n al Debate Educativo no ser\u00eda posible sin el engranaje de muchas piezas que hoy queremos agradecer:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Al alumnado:<\/strong> Luc\u00eda, Julio, Alejandro, Enrique, M\u00f3nica, Diego, Trist\u00e1n y \u00c1lvaro; por vuestras horas de investigaci\u00f3n, vuestro esfuerzo a deshoras, por las tardes, incluidos d\u00edas de fiesta, vuestro talento y por dejar el nombre de nuestro centro en lo m\u00e1s alto de Andaluc\u00eda.<\/li>\n\n\n\n<li><strong>Al profesorado implicado directamente:<\/strong> Hermenegildo, F\u00e1tima, Ana, Mercedes, Gloria, Manuela&#8230;; por vuestra gu\u00eda constante, por creer en el debate como herramienta educativa y por acompa\u00f1ar a estos j\u00f3venes en su crecimiento intelectual. Pero tambi\u00e9n <strong>al resto de profesores y profesoras <\/strong>que cambian fechas de pruebas, que ayudan adaptando sus contenidos para no perjudicar al equipo y que comprende que este esfuerzo tambi\u00e9n enriquece de alguna manera sus materias.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.22.47-1024x768.jpeg\" alt=\"\" class=\"wp-image-18037\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.22.47-1024x768.jpeg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.22.47-300x225.jpeg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.22.47-768x576.jpeg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.22.47-1536x1152.jpeg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.22.47-2048x1536.jpeg 2048w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.22.47-400x300.jpeg 400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>A la Directiva:<\/strong> Por el apoyo incondicional y por facilitar siempre el camino para que estas experiencias de \u00e9xito se hagan realidad.<\/li>\n\n\n\n<li><strong>A las familias:<\/strong> Por vuestro apoyo desde casa, siendo el pilar fundamental para que vuestros hijos e hijas lleguen tan lejos. Sabemos de la tesitura que supone apostar por la participaci\u00f3n en esta experiencia mientras deber\u00edan centrarse en otras cosas&#8230; Los frutos ya lo ver\u00e9is m\u00e1s adelante.<\/li>\n\n\n\n<li><strong>Al equipo swing<\/strong>: Carla, Julia, Ana R\u00edos y Ana Mendiz\u00e1bal; que han estado muy presentes en la preparaci\u00f3n de la fase auton\u00f3mica: sin su apoyo constante llegar tan lejos no hubiera sido posible. Seguid trabajando para igualar lo que vuestros compa\u00f1eros y compa\u00f1eras han conseguido este curso.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.46-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-18044\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.46-1-1024x768.jpeg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.46-1-300x225.jpeg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.46-1-768x576.jpeg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.46-1-1536x1152.jpeg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.46-1-400x300.jpeg 400w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.46-1.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\">M\u00f3nica en un momento del primer Debate en una Sala del Conservatorio profesional de Jerez<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.48-1-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-18045\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.48-1-1-1024x768.jpeg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.48-1-1-300x225.jpeg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.48-1-1-768x576.jpeg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.48-1-1-1536x1152.jpeg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.48-1-1-400x300.jpeg 400w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.48-1-1.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u00a1Gracias a todos por hacer que el IES L\u00f3pez de Arenas no deje de crecer! Seguimos debatiendo, seguimos aprendiendo. Y el a\u00f1o que viene, lo intentaremos de nuevo&#8230;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.53.06-1024x768.jpeg\" alt=\"\" class=\"wp-image-18056\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.53.06-1024x768.jpeg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.53.06-300x225.jpeg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.53.06-768x576.jpeg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.53.06-1536x1152.jpeg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.53.06-400x300.jpeg 400w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.53.06.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"18046\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.48-2-1024x768.jpeg\" alt=\"\" class=\"wp-image-18046\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.48-2-1024x768.jpeg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.48-2-300x225.jpeg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.48-2-768x576.jpeg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.48-2-1536x1152.jpeg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.48-2-400x300.jpeg 400w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-06-at-19.36.48-2.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 5 y 6 de mayo, Jerez de la Frontera se convirti\u00f3 en el epicentro de la palabra y el pensamiento cr\u00edtico en Andaluc\u00eda. El IES L\u00f3pez de Arenas acudi\u00f3 a la cita con una responsabilidad de altura: representar a &hellip; <a href=\"https:\/\/lopezdearenas.org\/inicio\/blog\/el-ies-lopez-de-arenas-brilla-en-la-fase-autonomica-del-torneo-de-debate-sevilla-tiene-nombre-de-marchena\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":82,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[5],"tags":[333,334,195],"class_list":["post-18035","post","type-post","status-publish","format-standard","hentry","category-novedades","tag-fase-regional","tag-oratoria-y-debate","tag-torneo-de-debate"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/posts\/18035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/comments?post=18035"}],"version-history":[{"count":6,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/posts\/18035\/revisions"}],"predecessor-version":[{"id":18060,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/posts\/18035\/revisions\/18060"}],"wp:attachment":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/media?parent=18035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/categories?post=18035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/tags?post=18035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}