{"id":11286,"date":"2022-11-18T00:37:56","date_gmt":"2022-11-17T23:37:56","guid":{"rendered":"https:\/\/lopezdearenas.org\/inicio\/blog\/?p=11286"},"modified":"2022-11-18T00:37:56","modified_gmt":"2022-11-17T23:37:56","slug":"jornadas-de-flamenco","status":"publish","type":"post","link":"https:\/\/lopezdearenas.org\/inicio\/blog\/jornadas-de-flamenco\/","title":{"rendered":"Jornadas de Flamenco"},"content":{"rendered":"\n<p>En la semana del 7 al 11 de noviembre alumnos y alumnas de nuestro centro han visitado la exposici\u00f3n sobre el Flamenco de Marchena de la asociaci\u00f3n ACUPAMAR&nbsp;en colaboraci\u00f3n con la Pe\u00f1a flamenca.. En ella han podido hacer un recorrido por las principales figuras flamencas que ha dado nuestro pueblo en las diferentes modalidades, cante, guitarra, baile. Los alumnos y alumnas han podido conocer un poco mejor a personajes como el Ni\u00f1o de Marchena o Pepe Palanca.<\/p>\n\n\n\n<p>Hemos visto un v\u00eddeo repasando el flamenco marchenero, una exposici\u00f3n de carteler\u00eda y diversos objetos como sombreros, guitarras, las llaves de la estatua de Pepe Marchena, etc.<\/p>\n\n\n\n<p>Para terminar, hemos visitado la Pe\u00f1a Flamenca, ubicada en el mismo edificio que la biblioteca, que muchos de los alumnos y alumnas no conocen. All\u00ed hemos recibido una peque\u00f1a charla sobre los palos y los tipos de flamenco y han visto en directo actuaciones de percusi\u00f3n y de cante y guitarra.<\/p>\n\n\n\n<p>Con esta experiencia, nuestros alumnos y alumnas se han acercado un poco m\u00e1s a nuestro patrimonio andaluz, entroncado con la celebraci\u00f3n del d\u00eda internacional del flamenco el 16 de noviembre.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11311\" data-id=\"11311\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0028-472x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0028-472x1024.jpg 472w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0028-138x300.jpg 138w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0028-708x1536.jpg 708w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0028.jpg 738w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11309\" data-id=\"11309\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0025-472x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0025-472x1024.jpg 472w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0025-138x300.jpg 138w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0025-708x1536.jpg 708w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0025.jpg 738w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"472\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11288\" data-id=\"11288\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0002-1024x472.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0002-1024x472.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0002-300x138.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0002-768x354.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0002-1536x708.jpg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0002-500x231.jpg 500w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0002.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"472\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11287\" data-id=\"11287\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0023-1024x472.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0023-1024x472.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0023-300x138.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0023-768x354.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0023-1536x708.jpg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0023-500x231.jpg 500w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0023.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11289\" data-id=\"11289\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0003-472x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0003-472x1024.jpg 472w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0003-138x300.jpg 138w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0003-708x1536.jpg 708w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0003.jpg 738w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11290\" data-id=\"11290\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0004-472x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0004-472x1024.jpg 472w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0004-138x300.jpg 138w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0004-708x1536.jpg 708w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0004.jpg 737w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11291\" data-id=\"11291\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0005-472x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0005-472x1024.jpg 472w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0005-138x300.jpg 138w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0005-708x1536.jpg 708w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0005.jpg 737w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11292\" data-id=\"11292\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0006-472x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0006-472x1024.jpg 472w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0006-138x300.jpg 138w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0006-708x1536.jpg 708w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0006.jpg 738w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"472\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11293\" data-id=\"11293\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0008-1024x472.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0008-1024x472.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0008-300x138.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0008-768x354.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0008-1536x708.jpg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0008-500x231.jpg 500w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0008.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11294\" data-id=\"11294\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0009-472x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0009-472x1024.jpg 472w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0009-138x300.jpg 138w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0009-708x1536.jpg 708w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0009.jpg 738w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11295\" data-id=\"11295\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0010-472x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0010-472x1024.jpg 472w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0010-138x300.jpg 138w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0010-708x1536.jpg 708w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0010.jpg 738w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"472\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11300\" data-id=\"11300\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0015-1024x472.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0015-1024x472.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0015-300x138.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0015-768x354.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0015-1536x708.jpg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0015-500x231.jpg 500w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0015.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11297\" data-id=\"11297\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0012-472x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0012-472x1024.jpg 472w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0012-138x300.jpg 138w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0012-708x1536.jpg 708w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0012.jpg 738w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"472\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11308\" data-id=\"11308\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0024-1024x472.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0024-1024x472.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0024-300x138.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0024-768x354.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0024-1536x708.jpg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0024-500x231.jpg 500w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0024.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11298\" data-id=\"11298\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0013-472x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0013-472x1024.jpg 472w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0013-138x300.jpg 138w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0013-708x1536.jpg 708w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0013.jpg 738w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"472\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11310\" data-id=\"11310\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0026-1024x472.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0026-1024x472.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0026-300x138.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0026-768x354.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0026-1536x708.jpg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0026-500x231.jpg 500w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0026.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11299\" data-id=\"11299\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0014-472x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0014-472x1024.jpg 472w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0014-138x300.jpg 138w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0014-708x1536.jpg 708w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0014.jpg 738w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11301\" data-id=\"11301\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0016-472x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0016-472x1024.jpg 472w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0016-138x300.jpg 138w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0016-708x1536.jpg 708w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0016.jpg 738w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11303\" data-id=\"11303\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0018-472x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0018-472x1024.jpg 472w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0018-138x300.jpg 138w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0018-708x1536.jpg 708w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0018.jpg 738w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"472\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11304\" data-id=\"11304\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0019-1024x472.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0019-1024x472.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0019-300x138.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0019-768x354.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0019-1536x708.jpg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0019-500x231.jpg 500w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0019.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"472\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11305\" data-id=\"11305\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0021-1024x472.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0021-1024x472.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0021-300x138.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0021-768x354.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0021-1536x708.jpg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0021-500x231.jpg 500w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0021.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11306\" data-id=\"11306\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0022-472x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0022-472x1024.jpg 472w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0022-138x300.jpg 138w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0022-708x1536.jpg 708w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0022.jpg 738w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"472\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11307\" data-id=\"11307\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0023-1-1024x472.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0023-1-1024x472.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0023-1-300x138.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0023-1-768x354.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0023-1-1536x708.jpg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0023-1-500x231.jpg 500w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221110-WA0023-1.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En la semana del 7 al 11 de noviembre alumnos y alumnas de nuestro centro han visitado la exposici\u00f3n sobre el Flamenco de Marchena de la asociaci\u00f3n ACUPAMAR&nbsp;en colaboraci\u00f3n con la Pe\u00f1a flamenca.. En ella han podido hacer un recorrido &hellip; <a href=\"https:\/\/lopezdearenas.org\/inicio\/blog\/jornadas-de-flamenco\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":80,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[5],"tags":[],"class_list":["post-11286","post","type-post","status-publish","format-standard","hentry","category-novedades"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/posts\/11286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/comments?post=11286"}],"version-history":[{"count":1,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/posts\/11286\/revisions"}],"predecessor-version":[{"id":11312,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/posts\/11286\/revisions\/11312"}],"wp:attachment":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/media?parent=11286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/categories?post=11286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/tags?post=11286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}