{"id":11231,"date":"2022-11-14T02:56:58","date_gmt":"2022-11-14T01:56:58","guid":{"rendered":"https:\/\/lopezdearenas.org\/inicio\/blog\/?p=11231"},"modified":"2022-11-21T02:18:58","modified_gmt":"2022-11-21T01:18:58","slug":"magnifico-encuentro-de-la-promocion-de-alumnos-as-1992-1997-del-ies-lopez-de-arenas-de-marchena-al-cumplirse-el-25-aniversario","status":"publish","type":"post","link":"https:\/\/lopezdearenas.org\/inicio\/blog\/magnifico-encuentro-de-la-promocion-de-alumnos-as-1992-1997-del-ies-lopez-de-arenas-de-marchena-al-cumplirse-el-25-aniversario\/","title":{"rendered":"<strong>MAGN\u00cdFICO ENCUENTRO DE LA PROMOCI\u00d3N DE ALUMNOS\/AS 1992-1997 DEL IES L\u00d3PEZ DE ARENAS DE MARCHENA AL CUMPLIRSE EL 25 ANIVERSARIO<\/strong>"},"content":{"rendered":"\n<p>El acto comenzaba con la intervenci\u00f3n de Juan Miguel Borrego director&nbsp; actual del Instituto, que realiz\u00f3 un an\u00e1lisis de las distintas leyes de educaci\u00f3n durante estos veinticinco a\u00f1os. Adem\u00e1s mencion\u00f3 los importantes premios obtenidos por el Instituto en los \u00faltimos a\u00f1os. Posteriormente, el profesor Juan A Zambrano, intervino como director de 1997, para analizar las distintas vicisitudes que pasaron hasta llegar a la inauguraci\u00f3n del Instituto actual. Agradeciendo la colaboraci\u00f3n de los alumnos y alumnas, profesores y profesoras y personal de administraci\u00f3n y de servicios la estrecha colaboraci\u00f3n, que hizo posible que durante las vacaciones de navidades se realizara pr\u00e1cticamente el traslado. Tambi\u00e9n felicit\u00f3 a los alumnos y alumnas de esta promoci\u00f3n que hicieron que llevar\u00e1n el nombre del Instituto por los Cert\u00e1menes Nacionales de Investigaci\u00f3n y que se consiguiera el Joaqu\u00edn Guichot con el proyecto de Simulaci\u00f3n de Empresas.<\/p>\n\n\n\n<p>A continuaci\u00f3n Jos\u00e9 A C\u00e1rdenas resalt\u00f3,&nbsp; que muy pocos Institutos pod\u00edan sentirse&nbsp; tan orgulloso de crear empresas en sus aulas, as\u00ed surgi\u00f3 la empresa marchenera Macelca S. Coop&nbsp; And. Adem\u00e1s se\u00f1al\u00f3 que el papel del profesorado en la formaci\u00f3n profesional es ayudar a insertar a sus alumnos en el mundo laboral. Sinti\u00e9ndose muy satisfecho porque el mantenimiento de las empresas de Marchena estuviera cubierto con alumnos del IES L\u00f3pez de Arenas.<\/p>\n\n\n\n<p>&nbsp;A continuaci\u00f3n&nbsp; Silvia Rodr\u00edguez coment\u00f3 como surgi\u00f3 la idea de reunir la promoci\u00f3n y destac\u00f3 el papel del profesorado del instituto, valorando su profesionalidad y entrega.<\/p>\n\n\n\n<p>Una vez finalizado el orden de intervenciones, por parte de la direcci\u00f3n del centro se entreg\u00f3 a todos los presentes, un recuerdo del acto, y posteriormente se gir\u00f3 una visita&nbsp; donde los alumnos y alumnas pudieron visitar sus aulas. Adem\u00e1s visitaron la biblioteca, laboratorios , Aula de Emprendimiento y Aula ATECA, donde se realiz\u00f3 una peque\u00f1a demostraci\u00f3n con gafas 3D a cargo del profesor Jos\u00e9 A P\u00e9rez.<\/p>\n\n\n\n<p>Finalizando el reencuentro con una comida en un restaurante de la localidad.<\/p>\n\n\n\n<p>Para consultar la noticia en \u00abLa voz de Marchena\u00bb pincha <a href=\"https:\/\/lavozdemarchena.es\/portada\/14659-los-alumnos-y-alumnas-de-la-promocion-1992-1997-del-ies-lopez-de-arenas-celebraron-el-25-aniversario-de-su-graduacion\" target=\"_blank\" rel=\"noreferrer noopener\">aqu\u00ed<\/a>.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11232\" data-id=\"11232\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0006-1024x768.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0006-1024x768.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0006-300x225.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0006-768x576.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0006-1536x1152.jpg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0006-400x300.jpg 400w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0006.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11233\" data-id=\"11233\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0003-768x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0003-768x1024.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0003-225x300.jpg 225w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0003-1152x1536.jpg 1152w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0003.jpg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11234\" data-id=\"11234\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0004-768x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0004-768x1024.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0004-225x300.jpg 225w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0004-1152x1536.jpg 1152w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0004.jpg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11235\" data-id=\"11235\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0005-1024x768.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0005-1024x768.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0005-300x225.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0005-768x576.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0005-1536x1152.jpg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0005-400x300.jpg 400w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0005.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11236\" data-id=\"11236\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0008-768x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0008-768x1024.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0008-225x300.jpg 225w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0008-1152x1536.jpg 1152w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0008.jpg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11237\" data-id=\"11237\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0009-768x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0009-768x1024.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0009-225x300.jpg 225w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0009-1152x1536.jpg 1152w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0009.jpg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11238\" data-id=\"11238\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0010-768x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0010-768x1024.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0010-225x300.jpg 225w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0010-1152x1536.jpg 1152w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0010.jpg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11239\" data-id=\"11239\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0011-1024x768.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0011-1024x768.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0011-300x225.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0011-768x576.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0011-1536x1152.jpg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0011-400x300.jpg 400w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0011.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11240\" data-id=\"11240\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0012-1024x768.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0012-1024x768.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0012-300x225.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0012-768x576.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0012-1536x1152.jpg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0012-400x300.jpg 400w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0012.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11241\" data-id=\"11241\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0013-1024x768.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0013-1024x768.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0013-300x225.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0013-768x576.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0013-1536x1152.jpg 1536w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0013-400x300.jpg 400w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0013.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11242\" data-id=\"11242\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0014-768x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0014-768x1024.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0014-225x300.jpg 225w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0014-1152x1536.jpg 1152w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA0014.jpg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-11243\" data-id=\"11243\" src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA00151-768x1024.jpg\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA00151-768x1024.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA00151-225x300.jpg 225w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA00151-1152x1536.jpg 1152w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/IMG-20221112-WA00151.jpg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<figure class=\"wp-block-video aligncenter\"><video controls src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/VID-20221112-WA0016-1.mp4\"><\/video><\/figure>\n\n\n\n<figure class=\"wp-block-video aligncenter\"><video controls src=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2022\/11\/VID-20221119-WA0001.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El acto comenzaba con la intervenci\u00f3n de Juan Miguel Borrego director&nbsp; actual del Instituto, que realiz\u00f3 un an\u00e1lisis de las distintas leyes de educaci\u00f3n durante estos veinticinco a\u00f1os. Adem\u00e1s mencion\u00f3 los importantes premios obtenidos por el Instituto en los \u00faltimos &hellip; <a href=\"https:\/\/lopezdearenas.org\/inicio\/blog\/magnifico-encuentro-de-la-promocion-de-alumnos-as-1992-1997-del-ies-lopez-de-arenas-de-marchena-al-cumplirse-el-25-aniversario\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":80,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[5],"tags":[],"class_list":["post-11231","post","type-post","status-publish","format-standard","hentry","category-novedades"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/posts\/11231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/comments?post=11231"}],"version-history":[{"count":5,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/posts\/11231\/revisions"}],"predecessor-version":[{"id":11318,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/posts\/11231\/revisions\/11318"}],"wp:attachment":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/media?parent=11231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/categories?post=11231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/tags?post=11231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}