{"id":4689,"date":"2016-07-24T12:08:01","date_gmt":"2016-07-24T11:08:01","guid":{"rendered":"http:\/\/lopezdearenas.org\/inicio\/blog\/?page_id=4689"},"modified":"2016-07-24T12:37:24","modified_gmt":"2016-07-24T11:37:24","slug":"huerto-escolar-ii","status":"publish","type":"page","link":"https:\/\/lopezdearenas.org\/inicio\/blog\/huerto-escolar-ii\/","title":{"rendered":"Huerto Escolar II (Curso 2015\/2016)"},"content":{"rendered":"<p>En el pasado curso escolar 2014-2015 present\u00e1bamos este proyecto con la finalidad de convertir nuestro centro educativo, el IES L\u00f3pez de Arenas de Marchena, \u201cen un lugar que posibilite al alumnado adquirir una nueva experiencia acerca del entorno natural, y desarrollar actitudes y responsabilidad medioambiental\u201d. Y nuestra intenci\u00f3n para este curso sigue siendo la misma, considerando que, adem\u00e1s del huerto propiamente dicho, hemos estado desarrollando otras iniciativas medioambientales para nuestro centro. Es el cuarto a\u00f1o en que el instituto participa en el Programa y el segundo con este proyecto concreto de huerto escolar. Trabajan en el proyecto 15 alumnos y alumnas de primero y segundo de ESO, algunos de los cuales ya lo hicieron en el anterior<\/p>\n<p><span style=\"color: #008000;\"><strong>Objetivos<\/strong><\/span><br \/>\n1.-Conocer los principales cultivos tradicionales en nuestra horticultura como base de una alimentaci\u00f3n y h\u00e1bitos de vida m\u00e1s saludables;<\/p>\n<p>2.-Conocer las herramientas b\u00e1sicas y las faenas necesarias para el cultivo en el huerto.<\/p>\n<p>3.- Favorecer el trabajo en grupo entre el alumnado, el profesorado y otras personas (padres, madres, abuelos y agricultores del entorno) que colaboran en el desarrollo del huerto.<\/p>\n<p>4.- Desarrollar la sensibilizaci\u00f3n ante las distintas problem\u00e1ticas ambientales.<\/p>\n<p>5.- Conocer un vocabulario propio de la agricultura.<\/p>\n<p>6.- Trabajar valores y actitudes como la convivencia, la autonom\u00eda, la solidaridad y el trabajo cooperativo.<\/p>\n<p><span style=\"color: #008000;\"><strong>Un proyecto con alcance interdisciplinar<\/strong><\/span><\/p>\n<p>Consideramos que a este proyecto que llevamos a cabo, igual que ocurre con cualquier otro que se desarrollen en un centro educativo, tiene la potencialidad de ayudar en el conocimiento y dominio de otras materias del curr\u00edculum, as\u00ed como en la adquisici\u00f3n de las competencias b\u00e1sicas elementales.<\/p>\n<p>Ciencias Naturales: el agua, los suelos, los seres vivos, la agricultura ecol\u00f3gica<br \/>\nCiencias Sociales; agricultura ecol\u00f3gica, recursos renovables, medio ambiente, vida rural y urbana, el comercio y el consumo<br \/>\nEducaci\u00f3n F\u00edsica: actividades al aire libre, la dieta sana y equilibrada<br \/>\nLengua castellana: mensajes publicitarios, refranes, vocabulario espec\u00edfico, preparaci\u00f3n de fichas<br \/>\nMatem\u00e1ticas: planos, croquis, c\u00e1lculos de superficies, estad\u00edsticas, gr\u00e1ficas, econom\u00eda del huerto<br \/>\nTecnolog\u00eda: herramientas, la palanca, sistema de riego<br \/>\nEducaci\u00f3n Pl\u00e1stica: dise\u00f1o de slogan y etiquetas, carteles<br \/>\nTemas transversales: educaci\u00f3n para la paz, consumo, salud, coeducaci\u00f3n, personas con discapacidad<\/p>\n<p><span style=\"color: #008000;\"><strong>Difusi\u00f3n del proyecto:<\/strong><\/span><\/p>\n<p>El Programa Andaluc\u00eda Profundiza dispone en el instituto de un instrumento TIC espec\u00edfico para su difusi\u00f3n, en concreto un blog en la que se viene colgando toda la informaci\u00f3n relativa al mismo. Existe un enlace en la web del Centro (www.lopezdearenas.org) que comunica directamente con la p\u00e1gina del proyecto.<\/p>\n<p>A su vez, se difundir\u00e1n los avances del proyecto a trav\u00e9s del peri\u00f3dico escolar El Barranco, dedicando una secci\u00f3n al programa en este tercer trimestre.<\/p>\n<p><span style=\"color: #008000;\"><strong>Desarrollo<\/strong><\/span><\/p>\n<p><strong>La primera sesi\u00f3n:<\/strong> tuvo lugar el 10 de marzo. En ella hicimos la <strong>presentaci\u00f3n del Proyecto al alumnado<\/strong>, los objetivos que perseguimos y la forma en que se iba a llevar a cabo. A continuaci\u00f3n, y en vistas de que ya est\u00e1bamos en primavera y deb\u00edamos iniciar las labores de horticultura propias, nos pusimos manos a la obra y comenzamos con las tareas de preparaci\u00f3n del terreno.<\/p>\n<p><strong>La segunda sesi\u00f3n:<\/strong>\u00a0el 18 de marzo, \u00faltimo d\u00eda del segundo trimestre, en colaboraci\u00f3n con nuestro compa\u00f1ero de Ciencias Naturales, Jos\u00e9 Mac\u00edas, la dedicamos a la plantaci\u00f3n de plantas arom\u00e1ticas por diversas zonas que rodean las pistas de recreo, as\u00ed como algunos arbustos: lavanda, romero y madro\u00f1os, proporcionados por la Delegaci\u00f3n Territorial dentro del programa Crece con tu \u00e1rbol, al que tambi\u00e9n pertenece el instituto. Tambi\u00e9n ese d\u00eda, con la colaboraci\u00f3n de la AMPA, nuestros alumnos y alumnas de Profundiza participaron en la elaboraci\u00f3n de jab\u00f3n con aceite usado dentro de una actividad global de final de trimestre.<\/p>\n<p><a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0002_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4692\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0002_2-1024x576.jpg\" alt=\"DSC_0002_2\" width=\"584\" height=\"329\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0002_2-1024x576.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0002_2-300x169.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0002_2-768x432.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0002_2-500x281.jpg 500w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a> <a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0012.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4693\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0012-1024x576.jpg\" alt=\"DSC_0012\" width=\"584\" height=\"329\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0012-1024x576.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0012-300x169.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0012-768x432.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0012-500x281.jpg 500w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a> <a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0019.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4694\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0019-1024x576.jpg\" alt=\"DSC_0019\" width=\"584\" height=\"329\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0019-1024x576.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0019-300x169.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0019-768x432.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0019-500x281.jpg 500w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a> <a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0005.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4695\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0005-576x1024.jpg\" alt=\"IMG-20160319-WA0005\" width=\"576\" height=\"1024\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0005-576x1024.jpg 576w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0005-169x300.jpg 169w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0005-768x1365.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0005.jpg 900w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a> <a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0007.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4696\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0007-576x1024.jpg\" alt=\"IMG-20160319-WA0007\" width=\"576\" height=\"1024\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0007-576x1024.jpg 576w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0007-169x300.jpg 169w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0007-768x1365.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0007.jpg 900w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a> <a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0009.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4697\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0009-1024x576.jpg\" alt=\"IMG-20160319-WA0009\" width=\"584\" height=\"329\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0009-1024x576.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0009-300x169.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0009-768x432.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0009-500x281.jpg 500w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0009.jpg 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a> <a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0019.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4698\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0019-576x1024.jpg\" alt=\"IMG-20160319-WA0019\" width=\"576\" height=\"1024\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0019-576x1024.jpg 576w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0019-169x300.jpg 169w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0019-768x1365.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160319-WA0019.jpg 900w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p><strong>En la tercera sesi\u00f3n:<\/strong> hicimos la plantaci\u00f3n de pimientos, tomates, berenjenas, calabacines, sand\u00edas y melones. Con anterioridad, una m\u00e1quina excavadora peque\u00f1a nivel\u00f3 y volte\u00f3 el terreno, y extendi\u00f3 una cuba de esti\u00e9rcol, que nos servir\u00eda de abono, pues l\u00f3gicamente, prescindimos de cualquier tipo de abono que no sea org\u00e1nico y ecol\u00f3gico. Tenemos que decir que esta parte del huerto es la segunda que creamos, pues no es la misma del curso pasado, sino una nueva junto a ella que nos ha permitido ampliar la que ya utiliz\u00e1bamos, de forma que la primera se ha dedicado a huerto de invierno, con las llamadas plantas verdes (ajo, cebollas, puerro, br\u00f3coli, lechuga, espinaca, acelga y col de bruselas), y que a esta fecha ya est\u00e1n todas cosechadas, salvo los ajos, y la segunda a los mencionados arriba, como productos de primavera.<\/p>\n<p>La tercera sesi\u00f3n la hemos dedicado a labores de limpieza de toda la zona y mantenimiento en general, incluyendo el arranque de malas hierbas, teniendo en cuenta que en el huerto de invierno, que se ha desarrollado desde octubre hasta mitad de mayo, ha crecido mucha hierba, sobre todo hortiga, pues es la \u00e9poca de lluvias abundantes adem\u00e1s de la temperatura casi primaveral que ha habido en los meses de invierno. De hecho, salvo unos d\u00edas en marzo con subida de temperaturas, no hemos tenido pr\u00e1cticamente necesidad de regar. Adem\u00e1s, repasamos los posibles fallos de una malla met\u00e1lica en todo el per\u00edmetro del huerto que colocamos el curso pasado, para impedir la entrada de roedores, pues ven\u00edamos observando su presencia en busca de comida y agua.<\/p>\n<p><a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0850.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4701\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0850-1024x576.jpg\" alt=\"DSC_0850\" width=\"584\" height=\"329\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0850-1024x576.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0850-300x169.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0850-768x432.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0850-500x281.jpg 500w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0850.jpg 1601w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a> <a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0869.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4702\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0869-576x1024.jpg\" alt=\"DSC_0869\" width=\"576\" height=\"1024\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0869-576x1024.jpg 576w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0869-169x300.jpg 169w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0869-768x1366.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0869.jpg 900w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a> <a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0895.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4703\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0895-1024x576.jpg\" alt=\"DSC_0895\" width=\"584\" height=\"329\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0895-1024x576.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0895-300x169.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0895-768x432.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0895-500x281.jpg 500w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/DSC_0895.jpg 1601w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/p>\n<p><strong>Cuarta sesi\u00f3n:<\/strong>\u00a0Desde el primer momento, a la hora del recreo nos venimos acercando al huerto a regar, ver la evoluci\u00f3n de las plantas y los frutos, quitar malas hierbas y dem\u00e1s tareas que requiere. Hemos comprobado que, como ocurri\u00f3 el curso pasado, al grupo inicial se han ido incorporando nuevos compa\u00f1eros que nos ped\u00edan poder participar en estas tareas. Desde marzo pudimos ir recogiendo cebollas, espinacas, acelgas y dem\u00e1s hortalizas de invierno, con la ilusi\u00f3n y el entusiasmo que supone para chicos y chicas de doce y trece a\u00f1os llegar a sus casas con productos de la huerta\u201dcriados\u201dEn esta cuarta sesi\u00f3n hemos hecho una <strong>recapitulaci\u00f3n de c\u00f3mo ha ido creciendo y tomando forma nuestro huerto, c\u00f3mo han aparecido las primeras flores y c\u00f3mo van madurando las primeros frutos.<\/strong><\/p>\n<p><a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0017.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4699\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0017-614x1024.jpg\" alt=\"IMG-20160604-WA0017\" width=\"584\" height=\"974\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0017-614x1024.jpg 614w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0017-180x300.jpg 180w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0017-768x1280.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0017.jpg 960w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/p>\n<p><strong>Quinta sesi\u00f3n:<\/strong>\u00a0Puesta en com\u00fan sobre el trabajo de investigaci\u00f3n y recogida de refranes, vocabulario espec\u00edfico de la agricultura tradicional de huertas, herramientas. Con anterioridad se le hab\u00eda encargado a un grupo de alumnos que hicieran este trabajo, que pudieron realizar acudiendo y preguntando a sus abuelos, padres, profesores. Algunos de ellos, pertenecientes a familias de agricultores, ten\u00edan un nivel muy aceptable de conocimientos de las herramientas y las faenas; otros nos dieron a conocer algunos de los muchos y variados refranes acerca de las faenas agr\u00edcolas y sobre el tiempo; y algunos aportaron una serie de palabras espec\u00edficas para esta rama del saber que a la vez son localismos, dado su uso restringido en nuestra localidad y la comarca.<\/p>\n<p><strong>Sexta sesi\u00f3n:<\/strong> Reportaje para nuestro peri\u00f3dico escolar El Barranco. Formamos dos grupos y cada uno de ellos se encarg\u00f3 de redactar varios aspectos de lo realizado hasta ese momento en el huerto. El resultado fue un art\u00edculo de dos p\u00e1ginas con sus correspondientes fotograf\u00edas y comentarios.<\/p>\n<p><a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150612-WA0008.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4708\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150612-WA0008-1024x768.jpg\" alt=\"IMG-20150612-WA0008\" width=\"584\" height=\"438\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150612-WA0008-1024x768.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150612-WA0008-300x225.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150612-WA0008-768x576.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150612-WA0008-400x300.jpg 400w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150612-WA0008.jpg 1280w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/p>\n<p><strong>S\u00e9ptima y octava sesiones<\/strong><\/p>\n<p>Construcci\u00f3n de una compostera. Dentro de la secci\u00f3n de medioambiente y ecolog\u00eda nos propusimos construir una compostera que nos permitiera elaborar nuestro propio esti\u00e9rcol ecol\u00f3gico, pues en ning\u00fan caso hemos utilizado abono sint\u00e9tico, sino esti\u00e9rcol animal; as\u00ed que a partir de ahora, podremos contar con uno y otro, el animal y el caser que salga de la compostera: Tras varias consulta en Internet sobre c\u00f3mo procede, nos inclinamos por la opci\u00f3n m\u00e1s c\u00f3moda de hacer y m\u00e1s barata a la vez. Nos hicimos con un cubo de pl\u00e1stico para basura de 100 litros de capacidad; a continuaci\u00f3n lo perforamos con un taladrador por la base y los laterales hasta una altura de unos veinte cent\u00edmetros desde la base, pues de esta manera permitimos que haya circulaci\u00f3n de aire, que junto con el calor y la humedad van a hacer que se descompongan los restos org\u00e1nicos que depositamos.<\/p>\n<p><a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0004.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4704\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0004-1024x614.jpg\" alt=\"IMG-20160604-WA0004\" width=\"584\" height=\"350\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0004-1024x614.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0004-300x180.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0004-768x461.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0004-500x300.jpg 500w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0004.jpg 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a> <a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0005.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4705\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0005-614x1024.jpg\" alt=\"IMG-20160604-WA0005\" width=\"584\" height=\"974\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0005-614x1024.jpg 614w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0005-180x300.jpg 180w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0005-768x1280.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0005.jpg 960w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a> <a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0016.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4706\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0016-1024x614.jpg\" alt=\"IMG-20160604-WA0016\" width=\"584\" height=\"350\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0016-1024x614.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0016-300x180.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0016-768x461.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0016-500x300.jpg 500w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0016.jpg 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a> <a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0020.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4707\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0020-614x1024.jpg\" alt=\"IMG-20160604-WA0020\" width=\"584\" height=\"974\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0020-614x1024.jpg 614w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0020-180x300.jpg 180w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0020-768x1280.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20160604-WA0020.jpg 960w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/p>\n<p>Por \u00faltimo, hicimos un agujero en el terreno del mismo di\u00e1metro que la base de la compostera, de forma que la coloquemos sobre este agujero y vaya cayendo en su interior el abono que se va formando dentro de ella. Ya no nos quedaba m\u00e1s que colocar una primera capa de ramas secas consistentes en el interior e ir depositando encima los elementos org\u00e1nicos que van a fermentar y convertirse en abono: hojas y malas hierbas del huerto, restos del desayuno como piel de fruta o pan, as\u00ed como restos de comida y desechos que quedan cuando preparamos en casa la cena o el almuerzo: mondas de patatas, de ajos, de cebollas, etc<\/p>\n<p>A partir de la segunda semana de mayo nos hemos dedicado a recoger los primeros productos que han ido madurando: los ajos, las cebollas\u2026 sembrados en noviembre, y los primeros tomates, que plantamos a principios de abril.<\/p>\n<p><a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150617-WA0005.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4709\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150617-WA0005-1024x614.jpg\" alt=\"IMG-20150617-WA0005\" width=\"584\" height=\"350\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150617-WA0005-1024x614.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150617-WA0005-300x180.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150617-WA0005-768x461.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150617-WA0005-500x300.jpg 500w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150617-WA0005.jpg 1100w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a> <a href=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150617-WA0006.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4710\" src=\"http:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150617-WA0006-1024x614.jpg\" alt=\"IMG-20150617-WA0006\" width=\"584\" height=\"350\" srcset=\"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150617-WA0006-1024x614.jpg 1024w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150617-WA0006-300x180.jpg 300w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150617-WA0006-768x461.jpg 768w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150617-WA0006-500x300.jpg 500w, https:\/\/lopezdearenas.org\/inicio\/blog\/wp-content\/uploads\/2016\/07\/IMG-20150617-WA0006.jpg 1100w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/p>\n<p>T\u00e9ngase en cuenta que adem\u00e1s de estas ocho sesiones que debemos realizar seg\u00fan marca la normativa espec\u00edfica del Programa Andaluc\u00eda Profundiza, desde finales de marzo hasta final de curso los alumnos y alumnas, junto con este coordinador y un profesor m\u00e1s, han estado realizando durante los recreos la labores de cuidado y mantenimiento del huerto, como el riego, retirada de malas hierbas, tratamiento ecol\u00f3gico contra plagas de hormigas y pulgones, repaso y vigilancia del sistema de goteo y recogida de los hortalizas. Pues por el proyecto de que se trata, no estamos ante una actividad a realizar s\u00f3lo en sesiones diferenciadas y separadas en el tiempo, sino que ha requerido la presencia y dedicaci\u00f3n constante a lo largo del tercer trimestre, incluyendo un d\u00eda del fin de semana para el riego en funci\u00f3n de las altas temperaturas que son habituales a partir de mayo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el pasado curso escolar 2014-2015 present\u00e1bamos este proyecto con la finalidad de convertir nuestro centro educativo, el IES L\u00f3pez de Arenas de Marchena, \u201cen un lugar que posibilite al alumnado adquirir una nueva experiencia acerca del entorno natural, y &hellip; <a href=\"https:\/\/lopezdearenas.org\/inicio\/blog\/huerto-escolar-ii\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4689","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/pages\/4689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/comments?post=4689"}],"version-history":[{"count":5,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/pages\/4689\/revisions"}],"predecessor-version":[{"id":4712,"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/pages\/4689\/revisions\/4712"}],"wp:attachment":[{"href":"https:\/\/lopezdearenas.org\/inicio\/blog\/wp-json\/wp\/v2\/media?parent=4689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}